{"id":6972,"count":1,"description":"","link":"https:\/\/voelkerrechtsblog.org\/de\/authors\/cathrin-zengerling\/","name":"Cathrin Zengerling","slug":"cathrin-zengerling","taxonomy":"authors","meta":[],"acf":{"detail_group":{"image":{"ID":16932,"id":16932,"title":"[:en]Zengerling-aspect-ratio-1-1[:]","filename":"Zengerling-aspect-ratio-1-1.png","filesize":42102,"url":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","link":"https:\/\/voelkerrechtsblog.org\/de\/zengerling-aspect-ratio-1-1\/","alt":"","author":"16","description":"","caption":"","name":"zengerling-aspect-ratio-1-1","status":"inherit","uploaded_to":0,"date":"2022-03-21 13:36:54","modified":"2022-03-21 13:36:54","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/voelkerrechtsblog.org\/wp-includes\/images\/media\/default.png","width":168,"height":168,"sizes":{"thumbnail":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","medium-width":168,"medium-height":168,"medium_large":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","medium_large-width":168,"medium_large-height":168,"large":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","large-width":168,"large-height":168,"1536x1536":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","1536x1536-width":168,"1536x1536-height":168,"2048x2048":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","2048x2048-width":168,"2048x2048-height":168,"2k":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","2k-width":168,"2k-height":168,"1600":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","1600-width":168,"1600-height":168,"small":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1.png","small-width":168,"small-height":168,"tyny":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1-150x150.png","tyny-width":150,"tyny-height":150,"cptm_icon":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-aspect-ratio-1-1-16x16.png","cptm_icon-width":16,"cptm_icon-height":16},"original_image":{"ID":16931,"id":16931,"title":"[:en]Zengerling[:]","filename":"Zengerling.png","filesize":48968,"url":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","link":"https:\/\/voelkerrechtsblog.org\/de\/zengerling\/","alt":"","author":"16","description":"","caption":"","name":"zengerling","status":"inherit","uploaded_to":0,"date":"2022-03-21 13:36:49","modified":"2022-03-21 13:36:49","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/voelkerrechtsblog.org\/wp-includes\/images\/media\/default.png","width":168,"height":200,"sizes":{"thumbnail":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","medium-width":168,"medium-height":200,"medium_large":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","medium_large-width":168,"medium_large-height":200,"large":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","large-width":168,"large-height":200,"1536x1536":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","1536x1536-width":168,"1536x1536-height":200,"2048x2048":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","2048x2048-width":168,"2048x2048-height":200,"2k":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","2k-width":168,"2k-height":200,"1600":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","1600-width":168,"1600-height":200,"small":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling.png","small-width":168,"small-height":200,"tyny":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-150x179.png","tyny-width":150,"tyny-height":179,"cptm_icon":"https:\/\/voelkerrechtsblog.org\/wp-content\/uploads\/2022\/03\/Zengerling-16x16.png","cptm_icon-width":16,"cptm_icon-height":16}}},"first_name":"Cathrin","last_name":"Zengerling","location":"","short_profile":"<p>Cathrin Zengerling<strong>\u00a0<\/strong>is a legal scholar and heads the junior professorship &#8220;Transformation to Sustainable Energy Systems&#8221; and the research group &#8220;Urban Footprints&#8221; at the University of Freiburg. She holds a PhD in international environmental law from the University of Hamburg and a Master of Laws from the University of Michigan.<\/p>\n","social_media":[{"network":"LinkedIn","url":"https:\/\/www.linkedin.com\/in\/cathrinzengerling\/ "}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/voelkerrechtsblog.org\/de\/wp-json\/wp\/v2\/authors\/6972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voelkerrechtsblog.org\/de\/wp-json\/wp\/v2\/authors"}],"about":[{"href":"https:\/\/voelkerrechtsblog.org\/de\/wp-json\/wp\/v2\/taxonomies\/authors"}],"wp:post_type":[{"href":"https:\/\/voelkerrechtsblog.org\/de\/wp-json\/wp\/v2\/posts?authors=6972"},{"href":"https:\/\/voelkerrechtsblog.org\/de\/wp-json\/wp\/v2\/articles?authors=6972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}